{"id":51,"date":"2014-08-19T12:27:13","date_gmt":"2014-08-19T10:27:13","guid":{"rendered":"http:\/\/deutscher-kinderverein.de\/en\/2014\/08\/19\/spenden-mit-paypal\/"},"modified":"2014-08-19T12:27:13","modified_gmt":"2014-08-19T10:27:13","slug":"spenden-mit-paypal","status":"publish","type":"post","link":"https:\/\/deutscher-kinderverein.de\/en\/spenden-mit-paypal\/","title":{"rendered":"Spenden mit PayPal"},"content":{"rendered":"<p>{loadposition position-13}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>{loadposition position-13}<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-51","post","type-post","status-publish","format-standard","hentry","category-helfen"],"_links":{"self":[{"href":"https:\/\/deutscher-kinderverein.de\/en\/wp-json\/wp\/v2\/posts\/51","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deutscher-kinderverein.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deutscher-kinderverein.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deutscher-kinderverein.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/deutscher-kinderverein.de\/en\/wp-json\/wp\/v2\/comments?post=51"}],"version-history":[{"count":0,"href":"https:\/\/deutscher-kinderverein.de\/en\/wp-json\/wp\/v2\/posts\/51\/revisions"}],"wp:attachment":[{"href":"https:\/\/deutscher-kinderverein.de\/en\/wp-json\/wp\/v2\/media?parent=51"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deutscher-kinderverein.de\/en\/wp-json\/wp\/v2\/categories?post=51"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deutscher-kinderverein.de\/en\/wp-json\/wp\/v2\/tags?post=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}