{"id":13,"count":1,"description":"","link":"https:\/\/deutscher-kinderverein.de\/en\/category\/projekte\/","name":"Projekte","slug":"projekte","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/deutscher-kinderverein.de\/en\/wp-json\/wp\/v2\/categories\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deutscher-kinderverein.de\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/deutscher-kinderverein.de\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/deutscher-kinderverein.de\/en\/wp-json\/wp\/v2\/posts?categories=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}